{"id":276,"date":"2021-12-09T15:25:50","date_gmt":"2021-12-09T18:25:50","guid":{"rendered":"https:\/\/www.fae.ufmg.br\/biblioteca\/?page_id=276"},"modified":"2022-04-20T10:14:18","modified_gmt":"2022-04-20T13:14:18","slug":"ficha-catalografica","status":"publish","type":"page","link":"https:\/\/www.fae.ufmg.br\/biblioteca\/ficha-catalografica\/","title":{"rendered":"Ficha Catalogr\u00e1fica"},"content":{"rendered":"\n<p>A Ficha Catalogr\u00e1fico ou Cataloga\u00e7\u00e3o na Fonte \u00e9 a descri\u00e7\u00e3o f\u00edsica e tem\u00e1tica de uma obra, de acordo com normas internacionais (AACR2 \u2013 Anglo-American Cataloging Rules \u2013 2. ed.).&nbsp;<\/p>\n\n\n\n<p>Obrigat\u00f3ria em monografias de especializa\u00e7\u00e3o, disserta\u00e7\u00f5es e teses defendidas na UFMG, fornece informa\u00e7\u00f5es bibliogr\u00e1ficas referentes \u00e0 obra, permitindo a sua identifica\u00e7\u00e3o e auxiliando no trabalho de processamento t\u00e9cnico.<\/p>\n\n\n\n<p>Para a elabora\u00e7\u00e3o da ficha catalogr\u00e1fica \u00e9 necess\u00e1rio o envio do <strong>arquivo completo<\/strong> com a <strong>vers\u00e3o final<\/strong> do seu trabalho e o seu <strong>ano <\/strong>de nascimento. A solicita\u00e7\u00e3o deve ser encaminhada para o e-mail: <strong>bibref@fae.ufmg.br<\/strong>, com c\u00f3pia para <strong>biblio@fae.ufmg.br<\/strong> (<em>para que a chefia da biblioteca possa acompanhar sua solicita\u00e7\u00e3o<\/em>).<\/p>\n\n\n\n<p>Observa\u00e7\u00f5es importantes:<\/p>\n\n\n\n<p>\u2022 Solicite a ficha catalogr\u00e1fica <strong>somente <\/strong>ap\u00f3s <strong>todas as altera\u00e7\u00f5es e edi\u00e7\u00f5es no trabalho estiverem conclu\u00eddas<\/strong> e o trabalho estiver pronto. A prioridade no trabalho \u00e9 para atendimento imediato das novas solicita\u00e7\u00f5es. As solicita\u00e7\u00f5es de altera\u00e7\u00e3o nas fichas catalogr\u00e1ficas j\u00e1 conclu\u00eddas n\u00e3o ter\u00e3o a mesma prioridade que a elabora\u00e7\u00e3o da ficha pela primeira vez.<\/p>\n\n\n\n<p>\u2022 O arquivo a ser anexado com a vers\u00e3o final do trabalho pode ser em <strong>formato PDF<\/strong>. Se for em formato .doc do Word, salve para vers\u00e3o <strong>Word 2003<\/strong> ou inferior. (a biblioteca da FaE n\u00e3o possui vers\u00f5es superiores a 2003 e muitas vezes n\u00e3o conseguimos fazer a convers\u00e3o de formato do documento, portanto, n\u00e3o conseguiremos abrir o arquivo).<\/p>\n\n\n\n<p>\u2022 O prazo para confec\u00e7\u00e3o da ficha catalogr\u00e1fica, na biblioteca da FaE\/UFMG, \u00e9 de uma semana.<\/p>\n\n\n\n<p>\u2022 A elabora\u00e7\u00e3o de fichas catalogr\u00e1ficas \u00e9 feita somente para <strong>teses e disserta\u00e7\u00f5es defendidas nos cursos de Mestrado e Doutorado oferecidos pela FAE\/UFMG<\/strong>. Para trabalhos defendidos em outras unidades acad\u00eamicas da UFMG, solicite a ficha na biblioteca da mesma unidade onde o curso foi realizado.<\/p>\n\n\n\n<p>\u2022 Quando a ficha catalogr\u00e1fica estiver conclu\u00edda ela ser\u00e1 enviada em resposta ao e-mail utilizado para fazer a solicita\u00e7\u00e3o. Tenha certeza de que sua caixa de entrada n\u00e3o tenha atingido a capacidade m\u00e1xima e, se estiver demorando para receber uma resposta verifique se resposta j\u00e1 n\u00e3o chegou e foi parar na sua caixa de span.<\/p>\n\n\n\n<p>\u2022 Ao incluir a ficha catalogr\u00e1fica em sua tese\/disserta\u00e7\u00e3o, verifique se o seu editor de textos est\u00e1 mantendo a formata\u00e7\u00e3o visual da ficha (principalmente o espa\u00e7amento entre linhas da ficha).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ficha Catalogr\u00e1fico ou Cataloga\u00e7\u00e3o na Fonte \u00e9 a descri\u00e7\u00e3o f\u00edsica e tem\u00e1tica de uma obra, de acordo com normas internacionais (AACR2 \u2013 Anglo-American Cataloging Rules \u2013 2. ed.).&nbsp; Obrigat\u00f3ria em monografias de especializa\u00e7\u00e3o, disserta\u00e7\u00f5es e teses defendidas na UFMG, fornece informa\u00e7\u00f5es bibliogr\u00e1ficas referentes \u00e0 obra, permitindo a sua identifica\u00e7\u00e3o e auxiliando no trabalho de processamento t\u00e9cnico. Para a elabora\u00e7\u00e3o da ficha catalogr\u00e1fica \u00e9 necess\u00e1rio o envio do arquivo completo com a vers\u00e3o final do seu trabalho e o seu ano de nascimento. A solicita\u00e7\u00e3o deve ser encaminhada para o e-mail: bibref@fae.ufmg.br, com c\u00f3pia para biblio@fae.ufmg.br (para que a chefia\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[]}},"_links":{"self":[{"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/pages\/276"}],"collection":[{"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/comments?post=276"}],"version-history":[{"count":3,"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/pages\/276\/revisions"}],"predecessor-version":[{"id":784,"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/pages\/276\/revisions\/784"}],"wp:attachment":[{"href":"https:\/\/www.fae.ufmg.br\/biblioteca\/wp-json\/wp\/v2\/media?parent=276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}